{"id":15512,"date":"2018-09-13T15:49:26","date_gmt":"2018-09-13T13:49:26","guid":{"rendered":"https:\/\/www.templars-route.eu\/?page_id=15512"},"modified":"2018-09-13T17:04:28","modified_gmt":"2018-09-13T15:04:28","slug":"loge-bazin","status":"publish","type":"page","link":"https:\/\/www.templars-route.eu\/fr\/loge-bazin\/","title":{"rendered":"La maison templi\u00e8re de la Loge Bazin"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbfull_width\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb][vc_column][vc_column_text]Quand, <strong>en 1255<\/strong>, les Templiers ach\u00e8tent au seigneur de Vendeuvre sa vaste \u00ab\u00a0for\u00eat du Der\u00a0\u00bb de <strong>1200 hectares<\/strong> (qui deviendra la for\u00eat du Temple), ils y \u00e9tablissent, la <strong>maison templi\u00e8re de La Loge Bazin, rattach\u00e9e \u00e0 la commanderie de Bonlieu.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Destin\u00e9e \u00e0 la<strong> gestion de la for\u00eat la plus grande que les Templiers aient achet\u00e9 en Occident<\/strong>, la maison de La Loge Bazin \u00e9tait implant\u00e9e, en lisi\u00e8re, dans une zone d\u00e9frich\u00e9e d\u2019une dizaine d\u2019hectares qui constituait son domaine agricole. Elle comptait quatre \u00e9tangs \u00e0 proximit\u00e9 des b\u00e2timents occup\u00e9s par les Templiers dont une chapelle et le logis du commandeur. Les documents anciens font \u00e9galement \u00e9tat, sur place, d\u2019une bergerie, d\u2019une tuilerie, de maisons et de granges.[\/vc_column_text][\/vc_column][vc_column][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbfull_width\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/4&Prime;][vc_empty_space][vc_single_image image=\u00a0\u00bb15513&Prime; img_size=\u00a0\u00bbmedium\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb qode_css_animation=\u00a0\u00bb\u00a0\u00bb][vc_column_text]<\/p>\n<p style=\"text-align: center\">Parcours templiers dans la For\u00eat du Temple<\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][vc_column width=\u00a0\u00bb3\/4&Prime;][vc_column_text]Les interrogatoires livrent le nom du dernier commandeur de la maison templi\u00e8re de \u00ab\u00a0Loages\u00a0\u00bb\u00a0: Pierre Picard de Bure qui figure parmi les plus vieux Templiers. \u00c2g\u00e9 de 60 ans, il pr\u00e9cise avoir \u00e9t\u00e9 fait templier trente ans plus t\u00f4t dans la chapelle de la commanderie de Bonlieu.<\/p>\n<p>&nbsp;<\/p>\n<p>La maison templi\u00e8re de La Loge Bazin est d\u00e9crite en ruine en 1558. Pour autant, <strong>les vestiges des remparts de terre et des foss\u00e9s restent visibles dans la for\u00eat<\/strong> tout comme les digues des quatre \u00e9tangs. L\u2019emplacement des zones d\u2019habitat est jonch\u00e9 de briques de terre cuite.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c0 l\u2019\u00e9poque hospitali\u00e8re, la for\u00eat du Temple fut g\u00e9r\u00e9e par la commanderie de Bonlieu, elle-m\u00eame rattach\u00e9e \u00e0 la commanderie de Troyes. Pour rappeler les droits de justice que poss\u00e9dait le commandeur, trois piloris \u00e9taient install\u00e9s en bordure des chemins qu\u2019empruntaient, pour se rendre dans la for\u00eat, les habitants des villages voisins (Amance, La Ville-aux-Bois (aujourd\u2019hui hameau d\u2019Amance) et La Villeneuve-au-Ch\u00eane.[\/vc_column_text][vc_empty_space][\/vc_column][vc_column][vc_column_text]Depuis 2015, une signal\u00e9tique jalonnant un parcours de 5, 5 km permet de comprendre comment et pourquoi ce domaine a \u00e9t\u00e9 structur\u00e9 par les Templiers.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>(Pour en savoir plus\u00a0: Val\u00e9rie Alani\u00e8ce et Fran\u00e7ois Gilet, <em>Les templiers dans la for\u00eat d\u2019Orient<\/em>, Troyes, 2015)[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbfull_width\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]<\/p>\n<h2>Coordonn\u00e9es<\/h2>\n<p>&nbsp;<\/p>\n<p><strong>Parcours sur les traces des Templiers<\/strong><br \/>\nRoute Foresti\u00e8re du Temple<br \/>\n10140 AMANCE<br \/>\nT\u00e9l\u00e9chargez votre itin\u00e9raire sur <a href=\"https:\/\/www.cirkwi.com\/fr\/circuit\/45698-sur-les-traces-des-templiers-en-foret-d-orient\" target=\"_blank\" rel=\"noopener\">www.cirkwi.com<\/a>[\/vc_column_text][vc_empty_space][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;]<div id='wrap_map_6a97cc9b8fc2c' class='ultimate-map-wrapper ult-adjust-bottom-margin ' style=' height:300px;'><div id='map_6a97cc9b8fc2c' data-map_override='0' class='ultimate_google_map wpb_content_element 0' style='width:100%;height:300px;'><\/div><\/div><script type='text\/javascript'>\n\t\t\t(function($) {\n  \t\t\t'use strict';\n\t\t\tvar map_map_6a97cc9b8fc2c = null;\n\t\t\tvar coordinate_map_6a97cc9b8fc2c;\n\t\t\tvar isDraggable = $(document).width() > 641 ? 'true' : 'true';\n\t\t\ttry\n\t\t\t{\n\t\t\t\tvar map_map_6a97cc9b8fc2c = null;\n\t\t\t\tvar coordinate_map_6a97cc9b8fc2c;\n\t\t\t\tcoordinate_map_6a97cc9b8fc2c = new google.maps.LatLng(48.294673, 4.438865);\n\t\t\t\tvar mapOptions=\n\t\t\t\t{\n\t\t\t\t\tzoom: 12,\n\t\t\t\t\tcenter: coordinate_map_6a97cc9b8fc2c,\n\t\t\t\t\tscaleControl: true,\n\t\t\t\t\tstreetViewControl: false,\n\t\t\t\t\tmapTypeControl: false,\n\t\t\t\t\tpanControl: false,\n\t\t\t\t\tzoomControl: false,\n\t\t\t\t\tscrollwheel: true,\n\t\t\t\t\tdraggable: isDraggable,\n\t\t\t\t\tzoomControlOptions: {\n\t\t\t\t\t\tposition: google.maps.ControlPosition.right_bottom\n\t\t\t\t\t},mapTypeId: google.maps.MapTypeId.roadmap,};var map_map_6a97cc9b8fc2c = new google.maps.Map(document.getElementById('map_6a97cc9b8fc2c'),mapOptions);\n\t\t\t\t\t\tvar x = 'infowindow_open_value';\n\t\t\t\t\t\tvar marker_map_6a97cc9b8fc2c = new google.maps.Marker({\n\t\t\t\t\t\tposition: new google.maps.LatLng('48.294673', '4.438865'),\n\t\t\t\t\t\tanimation:  google.maps.Animation.DROP,\n\t\t\t\t\t\tmap: map_map_6a97cc9b8fc2c,\n\t\t\t\t\t\ticon: ''\n\t\t\t\t\t});\tgoogle.maps.event.addListener(marker_map_6a97cc9b8fc2c, 'click', toggleBounce);}\n\t\t\tcatch(e){};\n\t\t\tjQuery(document).ready(function($){\n\t\t\t\tgoogle.maps.event.trigger(map_map_6a97cc9b8fc2c, 'resize');\n\t\t\t\t$(window).on('resize', function(){\n\t\t\t\t\tgoogle.maps.event.trigger(map_map_6a97cc9b8fc2c, 'resize');\n\t\t\t\t\tif(map_map_6a97cc9b8fc2c!=null)\n\t\t\t\t\t\tmap_map_6a97cc9b8fc2c.setCenter(coordinate_map_6a97cc9b8fc2c);\n\t\t\t\t});\n\t\t\t\t$('.ui-tabs').on('tabsactivate', function(event, ui) {\n\t\t\t\t   if($(this).find('.ultimate-map-wrapper').length > 0)\n\t\t\t\t\t{\n\t\t\t\t\t\tsetTimeout(function(){\n\t\t\t\t\t\t\t$(window).trigger('resize');\n\t\t\t\t\t\t},200);\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t\t$('.ui-accordion').on('accordionactivate', function(event, ui) {\n\t\t\t\t   if($(this).find('.ultimate-map-wrapper').length > 0)\n\t\t\t\t\t{\n\t\t\t\t\t\tsetTimeout(function(){\n\t\t\t\t\t\t\t$(window).trigger('resize');\n\t\t\t\t\t\t},200);\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t\t$(window).on('load',function(){\n\t\t\t\t\tsetTimeout(function(){\n\t\t\t\t\t\t$(window).trigger('resize');\n\t\t\t\t\t},200);\n\t\t\t\t});\n\t\t\t\t$('.ult_exp_section').on('select', function(){\n\t\t\t\t\tif($(map_map_6a97cc9b8fc2c).parents('.ult_exp_section'))\n\t\t\t\t\t{\n\t\t\t\t\t\tsetTimeout(function(){\n\t\t\t\t\t\t\t$(window).trigger('resize');\n\t\t\t\t\t\t},200);\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t\t$(document).on('onUVCModalPopupOpen', function(){\n\t\t\t\t\tif($(map_map_6a97cc9b8fc2c).parents('.ult_modal-content'))\n\t\t\t\t\t{\n\t\t\t\t\t\tsetTimeout(function(){\n\t\t\t\t\t\t\t$(window).trigger('resize');\n\t\t\t\t\t\t},200);\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t\t$(document).on('click','.ult_tab_li',function(){\n\t\t\t\t\t$(window).trigger('resize');\n\t\t\t\t\tsetTimeout(function(){\n\t\t\t\t\t\t$(window).trigger('resize');\n\t\t\t\t\t},200);\n\t\t\t\t});\n\t\t\t});\n\t\t\tfunction toggleBounce() {\n\t\t\t  if (marker_map_6a97cc9b8fc2c.getAnimation() != null) {\n\t\t\t\tmarker_map_6a97cc9b8fc2c.setAnimation(null);\n\t\t\t  } else {\n\t\t\t\tmarker_map_6a97cc9b8fc2c.setAnimation(google.maps.Animation.BOUNCE);\n\t\t\t  }\n\t\t\t}\n\t\t\t})(jQuery);\n\t\t\t<\/script>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbfull_width\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb][vc_column][vc_column_text]Quand, en 1255, les Templiers ach\u00e8tent au seigneur de Vendeuvre sa vaste \u00ab\u00a0for\u00eat du Der\u00a0\u00bb de 1200 hectares (qui deviendra la for\u00eat du Temple), ils y \u00e9tablissent, la maison templi\u00e8re de La Loge Bazin, rattach\u00e9e \u00e0 la commanderie&#8230;<\/p>\n","protected":false},"author":27,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-15512","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La maison templi\u00e8re de la Loge Bazin - Route du patrimoine templier - Templars Route European Federation (TREF)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.templars-route.eu\/fr\/loge-bazin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La maison templi\u00e8re de la Loge Bazin - Route du patrimoine templier - Templars Route European Federation (TREF)\" \/>\n<meta property=\"og:description\" content=\"[vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbfull_width\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb][vc_column][vc_column_text]Quand, en 1255, les Templiers ach\u00e8tent au seigneur de Vendeuvre sa vaste \u00ab\u00a0for\u00eat du Der\u00a0\u00bb de 1200 hectares (qui deviendra la for\u00eat du Temple), ils y \u00e9tablissent, la maison templi\u00e8re de La Loge Bazin, rattach\u00e9e \u00e0 la commanderie...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.templars-route.eu\/fr\/loge-bazin\/\" \/>\n<meta property=\"og:site_name\" content=\"Route du patrimoine templier - Templars Route European Federation (TREF)\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-13T15:04:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.templars-route.eu\/fr\/loge-bazin\/\",\"url\":\"https:\/\/www.templars-route.eu\/fr\/loge-bazin\/\",\"name\":\"La maison templi\u00e8re de la Loge Bazin - Route du patrimoine templier - Templars Route European Federation (TREF)\",\"isPartOf\":{\"@id\":\"https:\/\/www.templars-route.eu\/fr\/#website\"},\"datePublished\":\"2018-09-13T13:49:26+00:00\",\"dateModified\":\"2018-09-13T15:04:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.templars-route.eu\/fr\/loge-bazin\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.templars-route.eu\/fr\/loge-bazin\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.templars-route.eu\/fr\/loge-bazin\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.templars-route.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La maison templi\u00e8re de la Loge Bazin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.templars-route.eu\/fr\/#website\",\"url\":\"https:\/\/www.templars-route.eu\/fr\/\",\"name\":\"Route du patrimoine templier - Templars Route European Federation (TREF)\",\"description\":\"Valorisation of Templar heritage in Europe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.templars-route.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La maison templi\u00e8re de la Loge Bazin - Route du patrimoine templier - Templars Route European Federation (TREF)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.templars-route.eu\/fr\/loge-bazin\/","og_locale":"fr_FR","og_type":"article","og_title":"La maison templi\u00e8re de la Loge Bazin - Route du patrimoine templier - Templars Route European Federation (TREF)","og_description":"[vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbfull_width\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb][vc_column][vc_column_text]Quand, en 1255, les Templiers ach\u00e8tent au seigneur de Vendeuvre sa vaste \u00ab\u00a0for\u00eat du Der\u00a0\u00bb de 1200 hectares (qui deviendra la for\u00eat du Temple), ils y \u00e9tablissent, la maison templi\u00e8re de La Loge Bazin, rattach\u00e9e \u00e0 la commanderie...","og_url":"https:\/\/www.templars-route.eu\/fr\/loge-bazin\/","og_site_name":"Route du patrimoine templier - Templars Route European Federation (TREF)","article_modified_time":"2018-09-13T15:04:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.templars-route.eu\/fr\/loge-bazin\/","url":"https:\/\/www.templars-route.eu\/fr\/loge-bazin\/","name":"La maison templi\u00e8re de la Loge Bazin - Route du patrimoine templier - Templars Route European Federation (TREF)","isPartOf":{"@id":"https:\/\/www.templars-route.eu\/fr\/#website"},"datePublished":"2018-09-13T13:49:26+00:00","dateModified":"2018-09-13T15:04:28+00:00","breadcrumb":{"@id":"https:\/\/www.templars-route.eu\/fr\/loge-bazin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.templars-route.eu\/fr\/loge-bazin\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.templars-route.eu\/fr\/loge-bazin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.templars-route.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"La maison templi\u00e8re de la Loge Bazin"}]},{"@type":"WebSite","@id":"https:\/\/www.templars-route.eu\/fr\/#website","url":"https:\/\/www.templars-route.eu\/fr\/","name":"Route du patrimoine templier - Templars Route European Federation (TREF)","description":"Valorisation of Templar heritage in Europe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.templars-route.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.templars-route.eu\/fr\/wp-json\/wp\/v2\/pages\/15512\/"}],"collection":[{"href":"https:\/\/www.templars-route.eu\/fr\/wp-json\/wp\/v2\/pages\/"}],"about":[{"href":"https:\/\/www.templars-route.eu\/fr\/wp-json\/wp\/v2\/types\/page\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.templars-route.eu\/fr\/wp-json\/wp\/v2\/users\/27\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.templars-route.eu\/fr\/wp-json\/wp\/v2\/comments\/?post=15512"}],"version-history":[{"count":0,"href":"https:\/\/www.templars-route.eu\/fr\/wp-json\/wp\/v2\/pages\/15512\/revisions\/"}],"wp:attachment":[{"href":"https:\/\/www.templars-route.eu\/fr\/wp-json\/wp\/v2\/media\/?parent=15512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}